{"id":15964,"date":"2022-10-31T03:22:56","date_gmt":"2022-10-31T03:22:56","guid":{"rendered":"https:\/\/www.cellutrak.ca\/?p=15964"},"modified":"2025-06-09T21:34:03","modified_gmt":"2025-06-09T21:34:03","slug":"une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton","status":"publish","type":"post","link":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/","title":{"rendered":"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE  R\u00c9GIONALE DE HALTON."},"content":{"rendered":"<p><strong><em>L\u2019INDUSTRIE AGRICOLE \u00c9T\u00c9 CONFRONT\u00c9E AU VOL DE TRACTEUR EN PRINTEMPS 2020.<\/em><\/strong><\/p>\n<p><em>Mars 2020<\/em> &#8212; En fin mars dernier, un travailleur agricole a \u00e9t\u00e9 cibl\u00e9 pour un coup de vol de son \u00e9quipement lourd. Malheureusement pour<br \/>\nces voleurs, le client avait faite install\u00e9 un Cellutrak chez son concessionnaire KUBOTA sur l\u2019un des tracteurs CASE vol\u00e9s. Le dispositif de<br \/>\nsuivi GPS a enregistr\u00e9 tous les emplacements de la machine depuis le moment o\u00f9 elles ont \u00e9t\u00e9 vol\u00e9es jusqu\u2019\u00e0 leur destination finale. Un<br \/>\nmembre du service \u00e0 la client\u00e8le 24\/7 de Cellutrak a travaill\u00e9 directement avec la police r\u00e9gionale de Halton pour leur fournir toutes les<br \/>\ninformations en temps r\u00e9el. Cela comprend des captures d\u2019\u00e9crans ainsi que des rapports d\u00e9taill\u00e9s pour leur aider \u00e0 obtenir le mandat<br \/>\nn\u00e9cessaire.<\/p>\n<p>Selon un agent de la police r\u00e9gionale de Halton, \u00ab\u00c0 la suite du mandat, les deux tracteurs vol\u00e9s ainsi qu\u2019un troisi\u00e8me tracteur vol\u00e9 lors d\u2019un<br \/>\nautre incident ont tous \u00e9t\u00e9 retrouv\u00e9s gr\u00e2ce \u00e0 celui qui \u00e9tait munis d\u2019un dispositif. \u00bb Les agents se sont fi\u00e9s sur le syst\u00e8me de g\u00e9olocalisation<br \/>\nGPS en joignant leurs techniques d\u2019enqu\u00eate pour localiser et r\u00e9cup\u00e9rer les tracteurs vol\u00e9s.<\/p>\n<p>Le partenariat entre Cellutrak et Kubota s\u2019est av\u00e9r\u00e9 b\u00e9n\u00e9fique pour tous les fabricants de machinerie lourde. Le dispositif de suivi GPS<br \/>\nCellutrak est compatible sur toutes les marques de machines et se font install\u00e9s au garage de plusieurs concessionnaires certifi\u00e9s de<br \/>\nKubota dans la province. La solution a \u00e9t\u00e9 con\u00e7ue pour r\u00e9pondre aux besoins de nombreuses industries, notamment: la construction,<br \/>\nl\u2019am\u00e9nagement paysager, le d\u00e9neigement, la location, l\u2019agriculture et le gouvernement.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1p_OziYFuUp3_mIfeffG8iZJuc8qfRQS4\/view?usp=sharing\">Suivez le lien pour le communiqu\u00e9 de presse complet<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019INDUSTRIE AGRICOLE \u00c9T\u00c9 CONFRONT\u00c9E AU VOL DE TRACTEUR EN PRINTEMPS 2020. Mars 2020 &#8212; En fin mars dernier, un travailleur agricole a \u00e9t\u00e9 cibl\u00e9 pour un coup de vol de son \u00e9quipement lourd. Malheureusement pour ces voleurs, le client avait faite install\u00e9 un Cellutrak chez&#8230;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36],"tags":[],"class_list":["post-15964","post","type-post","status-publish","format-standard","hentry","category-communiques-de-presse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v26.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON. - Cellutrak<\/title>\n<meta name=\"description\" content=\"Plus de 350\u202f000\u202f$ en machinerie lourde vol\u00e9e, incluant des \u00e9quipements CASE, ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s en Ontario gr\u00e2ce au syst\u00e8me de rep\u00e9rage GPS Cellutrak et \u00e0 la police de Halton.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON.\" \/>\n<meta property=\"og:description\" content=\"Plus de 350\u202f000\u202f$ en machinerie lourde vol\u00e9e, incluant des \u00e9quipements CASE, ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s en Ontario gr\u00e2ce au syst\u00e8me de rep\u00e9rage GPS Cellutrak et \u00e0 la police de Halton.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/\" \/>\n<meta property=\"og:site_name\" content=\"Cellutrak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cellutrakgpstracking\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-31T03:22:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T21:34:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2022\/12\/PR-LinkPreview-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kika.dev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"kika.dev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/\"},\"author\":{\"name\":\"kika.dev\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/327bc29517ea3f18ff3e45582daa4f0f\"},\"headline\":\"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON.\",\"datePublished\":\"2022-10-31T03:22:56+00:00\",\"dateModified\":\"2025-06-09T21:34:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#organization\"},\"articleSection\":[\"Communiqu\u00e9s de presse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/\",\"url\":\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/\",\"name\":\"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON. - Cellutrak\",\"isPartOf\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#website\"},\"datePublished\":\"2022-10-31T03:22:56+00:00\",\"dateModified\":\"2025-06-09T21:34:03+00:00\",\"description\":\"Plus de 350\u202f000\u202f$ en machinerie lourde vol\u00e9e, incluant des \u00e9quipements CASE, ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s en Ontario gr\u00e2ce au syst\u00e8me de rep\u00e9rage GPS Cellutrak et \u00e0 la police de Halton.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cellutrak.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#website\",\"url\":\"https:\/\/www.cellutrak.ca\/fr\/\",\"name\":\"Cellutrak\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cellutrak.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#organization\",\"name\":\"Cellutrak\",\"url\":\"https:\/\/www.cellutrak.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png\",\"contentUrl\":\"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png\",\"width\":200,\"height\":200,\"caption\":\"Cellutrak\"},\"image\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cellutrakgpstracking\/\",\"https:\/\/www.linkedin.com\/company\/cellutrakgpstracking\/\",\"https:\/\/www.youtube.com\/@cellutrakgps\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/327bc29517ea3f18ff3e45582daa4f0f\",\"name\":\"kika.dev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dc2be307793c2ec131d5ed274fb03155?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dc2be307793c2ec131d5ed274fb03155?s=96&d=mm&r=g\",\"caption\":\"kika.dev\"},\"sameAs\":[\"https:\/\/www.cellutrak.ca\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON. - Cellutrak","description":"Plus de 350\u202f000\u202f$ en machinerie lourde vol\u00e9e, incluant des \u00e9quipements CASE, ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s en Ontario gr\u00e2ce au syst\u00e8me de rep\u00e9rage GPS Cellutrak et \u00e0 la police de Halton.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/","og_locale":"fr_FR","og_type":"article","og_title":"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON.","og_description":"Plus de 350\u202f000\u202f$ en machinerie lourde vol\u00e9e, incluant des \u00e9quipements CASE, ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s en Ontario gr\u00e2ce au syst\u00e8me de rep\u00e9rage GPS Cellutrak et \u00e0 la police de Halton.","og_url":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/","og_site_name":"Cellutrak","article_publisher":"https:\/\/www.facebook.com\/cellutrakgpstracking\/","article_published_time":"2022-10-31T03:22:56+00:00","article_modified_time":"2025-06-09T21:34:03+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2022\/12\/PR-LinkPreview-.jpg","type":"image\/jpeg"}],"author":"kika.dev","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"kika.dev","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/#article","isPartOf":{"@id":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/"},"author":{"name":"kika.dev","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/327bc29517ea3f18ff3e45582daa4f0f"},"headline":"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON.","datePublished":"2022-10-31T03:22:56+00:00","dateModified":"2025-06-09T21:34:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/"},"wordCount":336,"publisher":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#organization"},"articleSection":["Communiqu\u00e9s de presse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/","url":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/","name":"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON. - Cellutrak","isPartOf":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#website"},"datePublished":"2022-10-31T03:22:56+00:00","dateModified":"2025-06-09T21:34:03+00:00","description":"Plus de 350\u202f000\u202f$ en machinerie lourde vol\u00e9e, incluant des \u00e9quipements CASE, ont \u00e9t\u00e9 r\u00e9cup\u00e9r\u00e9s en Ontario gr\u00e2ce au syst\u00e8me de rep\u00e9rage GPS Cellutrak et \u00e0 la police de Halton.","breadcrumb":{"@id":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cellutrak.ca\/fr\/une-valeur-de-350-000-et-plus-de-machineries-lourdes-case-volees-et-retrouvees-en-ontario-grace-au-systeme-de-reperage-de-cellutrak-kubota-avec-laide-de-la-police-regionale-de-halton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cellutrak.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"UNE VALEUR DE 350 000 $ ET PLUS DE MACHINERIES LOURDES CASE VOL\u00c9ES ET RETROUV\u00c9ES EN ONTARIO GR\u00c2CE AU SYST\u00c8ME DE REP\u00c9RAGE DE CELLUTRAK-KUBOTA AVEC L\u2019AIDE DE LA POLICE R\u00c9GIONALE DE HALTON."}]},{"@type":"WebSite","@id":"https:\/\/www.cellutrak.ca\/fr\/#website","url":"https:\/\/www.cellutrak.ca\/fr\/","name":"Cellutrak","description":"","publisher":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cellutrak.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cellutrak.ca\/fr\/#organization","name":"Cellutrak","url":"https:\/\/www.cellutrak.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png","contentUrl":"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png","width":200,"height":200,"caption":"Cellutrak"},"image":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cellutrakgpstracking\/","https:\/\/www.linkedin.com\/company\/cellutrakgpstracking\/","https:\/\/www.youtube.com\/@cellutrakgps"]},{"@type":"Person","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/327bc29517ea3f18ff3e45582daa4f0f","name":"kika.dev","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dc2be307793c2ec131d5ed274fb03155?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dc2be307793c2ec131d5ed274fb03155?s=96&d=mm&r=g","caption":"kika.dev"},"sameAs":["https:\/\/www.cellutrak.ca\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts\/15964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/comments?post=15964"}],"version-history":[{"count":1,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts\/15964\/revisions"}],"predecessor-version":[{"id":19153,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts\/15964\/revisions\/19153"}],"wp:attachment":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/media?parent=15964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/categories?post=15964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/tags?post=15964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}