{"id":18526,"date":"2024-09-23T22:14:50","date_gmt":"2024-09-23T22:14:50","guid":{"rendered":"https:\/\/www.cellutrak.ca\/?p=18526"},"modified":"2025-06-09T21:04:52","modified_gmt":"2025-06-09T21:04:52","slug":"les-voleurs-de-voitures-ciblent-le-vacancer-de-niagra-falls-heureusement-le-systeme-gps-de-cellutrak-a-ete-installe-pour-aider-la-police-a-recuperer-le-ford-f150-raptor-vole-a-montreal","status":"publish","type":"post","link":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/","title":{"rendered":"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al"},"content":{"rendered":"<p><strong>Le Ford F150 Raptor 2023 est \u00e9valu\u00e9 \u00e0 150 000 $.<\/strong><\/p>\n<p><strong>Juillet 2024<\/strong> \u2014 Des voleurs de voitures \u00e9taient \u00e0 l\u2019aff\u00fbt \u00e0 Niagara Falls \u00e0 la recherche d\u2019une FORD F150. Ils en ont d\u00e9couvert un devant un h\u00f4tel au milieu de la nuit et l\u2019ont vol\u00e9. Lorsque le propri\u00e9taire de la Ford s\u2019est r\u00e9veill\u00e9 pour quitter son h\u00f4tel, il a d\u00e9couvert que sa voiture avait disparu. Savoir qu\u2019ils avaient install\u00e9 un appareil Cellutrak leur a donn\u00e9 confiance puisque le syst\u00e8me GPS Ford avait \u00e9t\u00e9 d\u00e9sactiv\u00e9.<\/p>\n<p><a href=\"http:\/\/www.cellutrak.ca\/wp-content\/uploads\/2024\/09\/CELLUTRAK_PR_202408_RaptorTheftStory_Cellutrak_D02R00FA_20240829_FR.pdf\">Cliquer ici pour t\u00e9l\u00e9charger le communiqu\u00e9 officiel en format PDF.<\/a><\/p>\n<h2>\u00c0 propos de Cellutrak<\/h2>\n<p>Cellutrak offre un portefeuille complet de solutions t\u00e9l\u00e9matiques de suivi GPS de type militaire; elle se sp\u00e9cialise dans la pr\u00e9vention du vol et la gestion de flotte pour les entreprises et les consommateurs. Cr\u00e9\u00e9e en Am\u00e9rique du Nord en 2009, Cellutrak est une filiale du leader international du GPS Ituran, une soci\u00e9t\u00e9 cot\u00e9e en bourse (Nasdaq : ITRN). Cellutrak propose la derni\u00e8re technologie en mati\u00e8re de mat\u00e9riel et de logiciel, con\u00e7ue pour r\u00e9duire les risques auxquels s\u2019exposent les propri\u00e9taires de v\u00e9hicules et pour augmenter la productivit\u00e9. La suite compl\u00e8te de fonctionnalit\u00e9s t\u00e9l\u00e9matiques de Cellutrak comprend le suivi en temps r\u00e9el, la d\u00e9sactivation \u00e0 distance du moteur, les alertes en temps r\u00e9el, la gestion de la maintenance, les rapports d\u00e9taill\u00e9s et bien plus encore. Cellutrak s\u2019engage \u00e0 fournir le meilleur service \u00e0 la client\u00e8le de l\u2019industrie, ce qui inclut son service d\u2019assistance en cas de vol 24\/7, ayant contribu\u00e9 \u00e0 r\u00e9cup\u00e9rer, dans diff\u00e9rents pays, des v\u00e9hicules d\u2019une valeur de plusieurs millions de dollars.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Ford F150 Raptor 2023 est \u00e9valu\u00e9 \u00e0 150 000 $. Juillet 2024 \u2014 Des voleurs de voitures \u00e9taient \u00e0 l\u2019aff\u00fbt \u00e0 Niagara Falls \u00e0 la recherche d\u2019une FORD F150. Ils en ont d\u00e9couvert un devant un h\u00f4tel au milieu de la nuit et l\u2019ont&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[36,37,6],"tags":[],"class_list":["post-18526","post","type-post","status-publish","format-standard","hentry","category-communiques-de-presse","category-histoires-a-succes","category-nouvelles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v26.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al - Cellutrak<\/title>\n<meta name=\"description\" content=\"Un Ford F-150 Raptor vol\u00e9 \u00e0 Montr\u00e9al a \u00e9t\u00e9 retrouv\u00e9 rapidement gr\u00e2ce au syst\u00e8me de suivi GPS de Cellutrak. Lisez l\u2019histoire compl\u00e8te de cette r\u00e9cup\u00e9ration.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al\" \/>\n<meta property=\"og:description\" content=\"Un Ford F-150 Raptor vol\u00e9 \u00e0 Montr\u00e9al a \u00e9t\u00e9 retrouv\u00e9 rapidement gr\u00e2ce au syst\u00e8me de suivi GPS de Cellutrak. Lisez l\u2019histoire compl\u00e8te de cette r\u00e9cup\u00e9ration.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/\" \/>\n<meta property=\"og:site_name\" content=\"Cellutrak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cellutrakgpstracking\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-23T22:14:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T21:04:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2022\/12\/PR-LinkPreview-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"kika.cmm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"kika.cmm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/\"},\"author\":{\"name\":\"kika.cmm\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/19260df8999b60f3b7af6ad513baef63\"},\"headline\":\"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al\",\"datePublished\":\"2024-09-23T22:14:50+00:00\",\"dateModified\":\"2025-06-09T21:04:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/\"},\"wordCount\":327,\"publisher\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#organization\"},\"articleSection\":[\"Communiqu\u00e9s de presse\",\"Histoires \u00e0 succ\u00e8s\",\"Nouvelles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/\",\"url\":\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/\",\"name\":\"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al - Cellutrak\",\"isPartOf\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#website\"},\"datePublished\":\"2024-09-23T22:14:50+00:00\",\"dateModified\":\"2025-06-09T21:04:52+00:00\",\"description\":\"Un Ford F-150 Raptor vol\u00e9 \u00e0 Montr\u00e9al a \u00e9t\u00e9 retrouv\u00e9 rapidement gr\u00e2ce au syst\u00e8me de suivi GPS de Cellutrak. Lisez l\u2019histoire compl\u00e8te de cette r\u00e9cup\u00e9ration.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cellutrak.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#website\",\"url\":\"https:\/\/www.cellutrak.ca\/fr\/\",\"name\":\"Cellutrak\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cellutrak.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#organization\",\"name\":\"Cellutrak\",\"url\":\"https:\/\/www.cellutrak.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png\",\"contentUrl\":\"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png\",\"width\":200,\"height\":200,\"caption\":\"Cellutrak\"},\"image\":{\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/cellutrakgpstracking\/\",\"https:\/\/www.linkedin.com\/company\/cellutrakgpstracking\/\",\"https:\/\/www.youtube.com\/@cellutrakgps\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/19260df8999b60f3b7af6ad513baef63\",\"name\":\"kika.cmm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8cc3be29796286bbe538a875dcc6574c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8cc3be29796286bbe538a875dcc6574c?s=96&d=mm&r=g\",\"caption\":\"kika.cmm\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al - Cellutrak","description":"Un Ford F-150 Raptor vol\u00e9 \u00e0 Montr\u00e9al a \u00e9t\u00e9 retrouv\u00e9 rapidement gr\u00e2ce au syst\u00e8me de suivi GPS de Cellutrak. Lisez l\u2019histoire compl\u00e8te de cette r\u00e9cup\u00e9ration.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/","og_locale":"fr_FR","og_type":"article","og_title":"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al","og_description":"Un Ford F-150 Raptor vol\u00e9 \u00e0 Montr\u00e9al a \u00e9t\u00e9 retrouv\u00e9 rapidement gr\u00e2ce au syst\u00e8me de suivi GPS de Cellutrak. Lisez l\u2019histoire compl\u00e8te de cette r\u00e9cup\u00e9ration.","og_url":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/","og_site_name":"Cellutrak","article_publisher":"https:\/\/www.facebook.com\/cellutrakgpstracking\/","article_published_time":"2024-09-23T22:14:50+00:00","article_modified_time":"2025-06-09T21:04:52+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2022\/12\/PR-LinkPreview-.jpg","type":"image\/jpeg"}],"author":"kika.cmm","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"kika.cmm","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/#article","isPartOf":{"@id":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/"},"author":{"name":"kika.cmm","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/19260df8999b60f3b7af6ad513baef63"},"headline":"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al","datePublished":"2024-09-23T22:14:50+00:00","dateModified":"2025-06-09T21:04:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/"},"wordCount":327,"publisher":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#organization"},"articleSection":["Communiqu\u00e9s de presse","Histoires \u00e0 succ\u00e8s","Nouvelles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/","url":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/","name":"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al - Cellutrak","isPartOf":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#website"},"datePublished":"2024-09-23T22:14:50+00:00","dateModified":"2025-06-09T21:04:52+00:00","description":"Un Ford F-150 Raptor vol\u00e9 \u00e0 Montr\u00e9al a \u00e9t\u00e9 retrouv\u00e9 rapidement gr\u00e2ce au syst\u00e8me de suivi GPS de Cellutrak. Lisez l\u2019histoire compl\u00e8te de cette r\u00e9cup\u00e9ration.","breadcrumb":{"@id":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cellutrak.ca\/fr\/cellutrak-recupere-un-ford-f150-raptor-vole-a-montreal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cellutrak.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Les voleurs de voitures ciblent le vacancer de Niagra Falls, heureusement le syst\u00e8me GPS de Cellutrak a \u00e9t\u00e9 install\u00e9 pour aider la police \u00e0 r\u00e9cup\u00e9rer le Ford F150 Raptor vol\u00e9 \u00e0 Montr\u00e9al"}]},{"@type":"WebSite","@id":"https:\/\/www.cellutrak.ca\/fr\/#website","url":"https:\/\/www.cellutrak.ca\/fr\/","name":"Cellutrak","description":"","publisher":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cellutrak.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.cellutrak.ca\/fr\/#organization","name":"Cellutrak","url":"https:\/\/www.cellutrak.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png","contentUrl":"https:\/\/www.cellutrak.ca\/wp-content\/uploads\/2021\/09\/CELLUTRAK-Social-Thumb.png","width":200,"height":200,"caption":"Cellutrak"},"image":{"@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cellutrakgpstracking\/","https:\/\/www.linkedin.com\/company\/cellutrakgpstracking\/","https:\/\/www.youtube.com\/@cellutrakgps"]},{"@type":"Person","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/19260df8999b60f3b7af6ad513baef63","name":"kika.cmm","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.cellutrak.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8cc3be29796286bbe538a875dcc6574c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8cc3be29796286bbe538a875dcc6574c?s=96&d=mm&r=g","caption":"kika.cmm"}}]}},"_links":{"self":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts\/18526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/comments?post=18526"}],"version-history":[{"count":1,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts\/18526\/revisions"}],"predecessor-version":[{"id":19127,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/posts\/18526\/revisions\/19127"}],"wp:attachment":[{"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/media?parent=18526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/categories?post=18526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cellutrak.ca\/fr\/wp-json\/wp\/v2\/tags?post=18526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}